{"id":16186,"date":"2026-02-05T15:46:55","date_gmt":"2026-02-05T14:46:55","guid":{"rendered":"https:\/\/samba-resille.org\/site\/?p=16186"},"modified":"2026-03-18T15:11:25","modified_gmt":"2026-03-18T14:11:25","slug":"obrigada-en-quete-de-liberation-seule-en-scene-un-spectacle-delaine-lopes","status":"publish","type":"post","link":"https:\/\/samba-resille.org\/site\/en\/2026\/02\/05\/obrigada-en-quete-de-liberation-seule-en-scene-un-spectacle-delaine-lopes\/","title":{"rendered":"Obrigada ! En qu\u00eate de lib\u00e9ration &#8211; SeulE en sc\u00e8ne, un spectacle d\u2019Elaine Lopes"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"16186\" class=\"elementor elementor-16186\" wpc-filter-elementor-widget=\"1\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-95190cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"95190cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9ab91e3\" data-id=\"9ab91e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f622e54 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"f622e54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"684\" height=\"1024\" src=\"https:\/\/samba-resille.org\/site\/wp-content\/uploads\/2026\/02\/Obrigadaaffche-V5-nov-24-684x1024.jpg\" class=\"attachment-large size-large wp-image-16144\" alt=\"\" srcset=\"https:\/\/samba-resille.org\/site\/wp-content\/uploads\/2026\/02\/Obrigadaaffche-V5-nov-24-684x1024.jpg 684w, https:\/\/samba-resille.org\/site\/wp-content\/uploads\/2026\/02\/Obrigadaaffche-V5-nov-24-200x300.jpg 200w, https:\/\/samba-resille.org\/site\/wp-content\/uploads\/2026\/02\/Obrigadaaffche-V5-nov-24-768x1150.jpg 768w, https:\/\/samba-resille.org\/site\/wp-content\/uploads\/2026\/02\/Obrigadaaffche-V5-nov-24-1025x1536.jpg 1025w, https:\/\/samba-resille.org\/site\/wp-content\/uploads\/2026\/02\/Obrigadaaffche-V5-nov-24-1367x2048.jpg 1367w, https:\/\/samba-resille.org\/site\/wp-content\/uploads\/2026\/02\/Obrigadaaffche-V5-nov-24-8x12.jpg 8w, https:\/\/samba-resille.org\/site\/wp-content\/uploads\/2026\/02\/Obrigadaaffche-V5-nov-24-32x48.jpg 32w, https:\/\/samba-resille.org\/site\/wp-content\/uploads\/2026\/02\/Obrigadaaffche-V5-nov-24-scaled.jpg 1402w\" sizes=\"(max-width: 684px) 100vw, 684px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3e351a5\" data-id=\"3e351a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8086273 elementor-widget elementor-widget-text-editor\" data-id=\"8086273\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span style=\"font-weight: 400;\">Obrigada ! En qu\u00eate de lib\u00e9ration &#8211; SeulE en sc\u00e8ne<br \/><\/span><span style=\"font-weight: 400;\">Un spectacle d\u2019Elaine Lopes<\/span><\/h4><p><strong>Le 21 f\u00e9vrier dans le cadre de la semaine Kairos <\/strong><\/p><p><strong>Th\u00e9\u00e2tre et chant<br \/>20h30, Prix libre \u00e0 partir de 5 \u20ac<br \/><\/strong>Dur\u00e9e :<strong> 1h<br \/><\/strong>De et avec :<strong> Elaine Lopes<br \/><\/strong>Mise en sc\u00e8ne :<strong> Eva Glorian<br \/><\/strong>Co-\u00e9criture :<strong> Yannik D\u2019Elboux et Marc Fauroux<br \/><br \/><\/strong><\/p><p><span style=\"font-weight: 400;\">Obrigada ! En qu\u00eate de lib\u00e9ration est \u00e0 la fois <strong>dr\u00f4le, \u00e9mouvant et profond\u00e9ment intime.<\/strong> \u00c0 travers une autofiction sensible, Elaine Lopes plonge dans ses racines br\u00e9siliennes, rend hommage \u00e0 ses parents et \u00e0 ses anc\u00eatres et interroge les chemins de l\u2019<strong>\u00e9mancipation personnelle et collective<\/strong>. Port\u00e9 par le chant et le jeu th\u00e9\u00e2tral, le spectacle tisse un dialogue entre<strong> m\u00e9moire, identit\u00e9 et transmission et invite le public \u00e0 une travers\u00e9e o\u00f9 l\u2019intime devient politique<\/strong>.<br \/><br \/><\/span><\/p><p><span style=\"font-weight: 400;\"><strong>Chanteuse, auteure-interpr\u00e8te et com\u00e9dienne br\u00e9silienne<\/strong> n\u00e9e \u00e0 Santos, Elaine Lopes s\u2019installe en France en 2003. Depuis, elle d\u00e9veloppe un parcours artistique et p\u00e9dagogique riche, nourri de collaborations et de projets ancr\u00e9s dans la sc\u00e8ne toulousaine, tels que \u00c2me Sereine, Duo Leve ou Saravah Duo. Form\u00e9e au Br\u00e9sil aux Sciences de l\u2019\u00c9ducation, \u00e0 la danse, au chant et \u00e0 la com\u00e9die, elle poursuit en France une formation en chant et coaching vocal \u00e0 l\u2019Universit\u00e9 Toulouse II Jean Jaur\u00e8s, ainsi qu\u2019en musicoth\u00e9rapie. \u00c0 20 ans, elle anime pendant pr\u00e8s de dix ans des ateliers de danse et de th\u00e9\u00e2tre dans des quartiers populaires du Guaruj\u00e1 (Br\u00e9sil), une exp\u00e9rience fondatrice qui fa\u00e7onne durablement sa vision de la transmission artistique, centr\u00e9e sur l\u2019accueil de l\u2019autre dans sa globalit\u00e9 et son authenticit\u00e9. <strong>En 2024, elle cr\u00e9e la Cie ChanteSabi\u00e1 et revient \u00e0 ses premiers amours de com\u00e9dienne avec Obrigada ! En qu\u00eate de lib\u00e9ration.<br \/><br \/><\/strong><\/span><\/p><div>Le teaser du spectacle\u00a0:\u00a0\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=hT4vbsgro6Q\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.youtube.com\/watch?v%3DhT4vbsgro6Q&amp;source=gmail&amp;ust=1770376319498000&amp;usg=AOvVaw1qwAHvrwg99Hj1VOQO7pLI\">https:\/\/www.<wbr \/>youtube.com\/watch?v=<wbr \/>hT4vbsgro6Q<\/a><\/div><div>Son site internet : <a href=\"https:\/\/elainelopesartista.wixsite.com\/elainelopesvoix\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/elainelopesartista.wixsite.com\/elainelopesvoix&amp;source=gmail&amp;ust=1770376319498000&amp;usg=AOvVaw3sux7aY8fp2bi2tJiRYxkc\">https:\/\/elainelopesartista.<wbr \/>wixsite.com\/elainelopesvoix<\/a><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Obrigada ! En qu\u00eate de lib\u00e9ration &#8211; SeulE en sc\u00e8ne. Un spectacle d\u2019Elaine Lopes<br \/>\nTh\u00e9\u00e2tre et chant \/ Le 20 f\u00e9vrier \u00e0 20h30<\/p>","protected":false},"author":3,"featured_media":16145,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40,45],"tags":[],"class_list":["post-16186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenement","category-evenements-passes"],"_links":{"self":[{"href":"https:\/\/samba-resille.org\/site\/en\/wp-json\/wp\/v2\/posts\/16186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/samba-resille.org\/site\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/samba-resille.org\/site\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/samba-resille.org\/site\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/samba-resille.org\/site\/en\/wp-json\/wp\/v2\/comments?post=16186"}],"version-history":[{"count":8,"href":"https:\/\/samba-resille.org\/site\/en\/wp-json\/wp\/v2\/posts\/16186\/revisions"}],"predecessor-version":[{"id":16383,"href":"https:\/\/samba-resille.org\/site\/en\/wp-json\/wp\/v2\/posts\/16186\/revisions\/16383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/samba-resille.org\/site\/en\/wp-json\/wp\/v2\/media\/16145"}],"wp:attachment":[{"href":"https:\/\/samba-resille.org\/site\/en\/wp-json\/wp\/v2\/media?parent=16186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/samba-resille.org\/site\/en\/wp-json\/wp\/v2\/categories?post=16186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/samba-resille.org\/site\/en\/wp-json\/wp\/v2\/tags?post=16186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}